{"id":3113,"date":"2025-09-14T20:46:12","date_gmt":"2025-09-14T23:46:12","guid":{"rendered":"https:\/\/tq.dcmmarketingdigital.com.br\/marcas\/sanol\/?post_type=produtos&#038;p=3113"},"modified":"2025-09-14T20:46:13","modified_gmt":"2025-09-14T23:46:13","slug":"antimofo-sanol-original-5l","status":"publish","type":"produtos","link":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/","title":{"rendered":"Antimofo Sanol Original 5L"},"content":{"rendered":"\n<p>Elimina 99,9 % de bact\u00e9rias, fungos e mofo com f\u00f3rmula pronta para uso e aplica\u00e7\u00e3o pr\u00e1tica. Ao pulverizar sobre gavetas, estofados ou dentro de arm\u00e1rios, deixa um aroma suave de lavanda que perfuma discretamente o ambiente enquanto trata e previne o mofo e os maus odores. A fragr\u00e2ncia transmite sensa\u00e7\u00e3o de limpeza fresca e leve, deixando os espa\u00e7os mais agrad\u00e1veis e protegidos.<\/p>\n\n\n\n<p><strong>Volumetria:<\/strong> 330ml e 5L<br><strong>Local de uso:<\/strong> Arm\u00e1rios, gavetas, roupas, estofados e \u00e1reas \u00famidas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elimina 99,9 % de bact\u00e9rias, fungos e mofo com f\u00f3rmula pronta para uso e aplica\u00e7\u00e3o pr\u00e1tica. Ao pulverizar sobre gavetas, estofados ou dentro de arm\u00e1rios, deixa um aroma suave de lavanda que perfuma discretamente o ambiente enquanto trata e previne o mofo e os maus odores. A fragr\u00e2ncia transmite sensa\u00e7\u00e3o de limpeza fresca e leve, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3110,"parent":3108,"menu_order":0,"template":"","meta":{"footnotes":""},"categories":[21],"class_list":["post-3113","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","category-a7"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antimofo Sanol Original 5L - Sanol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antimofo Sanol Original 5L - Sanol\" \/>\n<meta property=\"og:description\" content=\"Elimina 99,9 % de bact\u00e9rias, fungos e mofo com f\u00f3rmula pronta para uso e aplica\u00e7\u00e3o pr\u00e1tica. Ao pulverizar sobre gavetas, estofados ou dentro de arm\u00e1rios, deixa um aroma suave de lavanda que perfuma discretamente o ambiente enquanto trata e previne o mofo e os maus odores. A fragr\u00e2ncia transmite sensa\u00e7\u00e3o de limpeza fresca e leve, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanol\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-14T23:46:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/\",\"url\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/\",\"name\":\"Antimofo Sanol Original 5L - Sanol\",\"isPartOf\":{\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png\",\"datePublished\":\"2025-09-14T23:46:12+00:00\",\"dateModified\":\"2025-09-14T23:46:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#primaryimage\",\"url\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png\",\"contentUrl\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png\",\"width\":675,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antimofo Sanol Original 330ml\",\"item\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Antimofo Sanol Original 5L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#website\",\"url\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/\",\"name\":\"Sanol\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#organization\",\"name\":\"Sanol\",\"url\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/08\/cropped-Logo-Sanol.png\",\"contentUrl\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/08\/cropped-Logo-Sanol.png\",\"width\":1417,\"height\":1005,\"caption\":\"Sanol\"},\"image\":{\"@id\":\"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antimofo Sanol Original 5L - Sanol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/","og_locale":"pt_BR","og_type":"article","og_title":"Antimofo Sanol Original 5L - Sanol","og_description":"Elimina 99,9 % de bact\u00e9rias, fungos e mofo com f\u00f3rmula pronta para uso e aplica\u00e7\u00e3o pr\u00e1tica. Ao pulverizar sobre gavetas, estofados ou dentro de arm\u00e1rios, deixa um aroma suave de lavanda que perfuma discretamente o ambiente enquanto trata e previne o mofo e os maus odores. A fragr\u00e2ncia transmite sensa\u00e7\u00e3o de limpeza fresca e leve, [&hellip;]","og_url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/","og_site_name":"Sanol","article_modified_time":"2025-09-14T23:46:13+00:00","og_image":[{"width":675,"height":768,"url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/","url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/","name":"Antimofo Sanol Original 5L - Sanol","isPartOf":{"@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#primaryimage"},"image":{"@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#primaryimage"},"thumbnailUrl":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png","datePublished":"2025-09-14T23:46:12+00:00","dateModified":"2025-09-14T23:46:13+00:00","breadcrumb":{"@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#primaryimage","url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png","contentUrl":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/09\/sanol-a7-antimofo-5l.png","width":675,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/antimofo-sanol-original-5l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/"},{"@type":"ListItem","position":3,"name":"Antimofo Sanol Original 330ml","item":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/produtos\/antimofo-sanol-original-330ml\/"},{"@type":"ListItem","position":4,"name":"Antimofo Sanol Original 5L"}]},{"@type":"WebSite","@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#website","url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/","name":"Sanol","description":"","publisher":{"@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#organization","name":"Sanol","url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#\/schema\/logo\/image\/","url":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/08\/cropped-Logo-Sanol.png","contentUrl":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-content\/uploads\/2025\/08\/cropped-Logo-Sanol.png","width":1417,"height":1005,"caption":"Sanol"},"image":{"@id":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/produtos\/3113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/produtos\/3113\/revisions"}],"predecessor-version":[{"id":3115,"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/produtos\/3113\/revisions\/3115"}],"up":[{"embeddable":true,"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/produtos\/3108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/media\/3110"}],"wp:attachment":[{"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/media?parent=3113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.totalquimicaoficial.com.br\/sanol\/wp-json\/wp\/v2\/categories?post=3113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}